{"id":105,"count":26,"description":"Nos housses de coussins en laine sont tiss\u00e9s \u00e0 la main. Nos tisserandes choisissent librement les teintes du motif brod\u00e9 ou nou\u00e9, ainsi, chaque pi\u00e8ce est absolument unique.\r\n\r\nLes pi\u00e8ces en stock sont disponibles imm\u00e9diatement et sont identiques \u00e0 la photo. Les housses de coussin en pr\u00e9-commande sont r\u00e9alis\u00e9s sous un d\u00e9lai de 2 \u00e0 3 mois. Leur photo est illustrative.","link":"https:\/\/po-paris.com\/en\/product-category\/tissages\/coussins\/coussins-en-laine\/","name":"Wool cushions","slug":"coussins-en-laine","taxonomy":"product_cat","parent":31,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/po-paris.com\/en\/wp-json\/wp\/v2\/product_cat\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/po-paris.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/po-paris.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/po-paris.com\/en\/wp-json\/wp\/v2\/product_cat\/31"}],"wp:post_type":[{"href":"https:\/\/po-paris.com\/en\/wp-json\/wp\/v2\/product?product_cat=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}